{"id":979,"count":3,"description":"Nos <strong>VTT \u00e9lectriques<\/strong> sont con\u00e7us pour vous offrir une exp\u00e9rience inoubliable, que vous soyez en altitude ou \u00e0 travers des r\u00e9gions vallonn\u00e9es. Repoussez vos limites avec ces v\u00e9los qui allient performance et plaisir du pilote. Que vous optiez pour une randonn\u00e9e tranquille ou une aventure plus intense, nos mod\u00e8les sont con\u00e7us pour vous permettre de vous d\u00e9penser, de vous amuser et de vous r\u00e9inventer. Lancez-vous dans l\u2019aventure avec nos VTTAE !","link":"https:\/\/www.o2feel.com\/ch\/categorie-produit\/velos-electriques-sport\/","name":"V\u00e9los \u00e9lectriques Sport","slug":"velos-electriques-sport","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":7,"_links":{"self":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product_cat\/979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product?product_cat=979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}