{"id":46223,"date":"2021-06-29T14:18:15","date_gmt":"2021-06-29T12:18:15","guid":{"rendered":"https:\/\/www.o2feel.com\/produit\/iswan-city-boost-7-1\/"},"modified":"2025-04-16T10:56:23","modified_gmt":"2025-04-16T08:56:23","slug":"iswan-7","status":"publish","type":"product","link":"https:\/\/www.o2feel.com\/ch\/produit\/iswan-7\/","title":{"rendered":"iSwan 7"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"46223\" class=\"elementor elementor-46223 elementor-2783\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-200ac5a elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"200ac5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b79acd elementor-widget elementor-widget-spacer\" data-id=\"9b79acd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31bc8de e-con-full e-flex e-con e-parent\" data-id=\"31bc8de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f83484 elementor-widget elementor-widget-image\" data-id=\"4f83484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/store-o2feel.fr\/8-velos-reconditionnes\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2050\" height=\"278\" src=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-scaled.jpg\" class=\"attachment-full size-full wp-image-104779\" alt=\"\" srcset=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-scaled.jpg 2050w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-300x41.jpg 300w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-1024x139.jpg 1024w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-768x104.jpg 768w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-1536x208.jpg 1536w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-2048x278.jpg 2048w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-220x30.jpg 220w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-1920x260.jpg 1920w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/12\/banniere-reconditionne-produit-800x108.jpg 800w\" sizes=\"(max-width: 2050px) 100vw, 2050px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1383ed7 e-flex e-con-boxed e-con e-parent\" data-id=\"1383ed7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db25261 elementor-widget elementor-widget-spacer\" data-id=\"db25261\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49ab19db elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"49ab19db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-183bf5a9\" data-id=\"183bf5a9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55717be0 testtest elementor-widget elementor-widget-heading\" data-id=\"55717be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00c9COUVERTE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fa7f7b elementor-widget elementor-widget-text-editor\" data-id=\"8fa7f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tdu v\u00e9lo\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60b29ecd\" data-id=\"60b29ecd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afd18e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afd18e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cb246ef\" data-id=\"5cb246ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6966ddb3 elementor-widget elementor-widget-spacer\" data-id=\"6966ddb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f76b6ef elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6f76b6ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17ede53c\" data-id=\"17ede53c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-145276a6 elementor-widget elementor-widget-text-editor\" data-id=\"145276a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;iSwan 7 incarne l&#8217;\u00e9l\u00e9gance, le confort et le chic, id\u00e9al pour un environnement urbain.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50aa87f8 elementor-widget elementor-widget-toggle\" data-id=\"50aa87f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1351\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1351\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened far fa-window-minimize\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Lire plus<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1351\"><p>\u00c9quip\u00e9 des technologies les plus avanc\u00e9es du march\u00e9 du v\u00e9lo \u00e9lectrique, il combine un moyeu Nexus 5 vitesses, un moteur Shimano E6100, une courroie Gates, et une batterie O2feel garantie 4 ans (sous r\u00e9serve d&#8217;enregistrement sur le site O2feel). Un assemblage parfait de composants pour r\u00e9pondre aux besoins exigeants des cyclistes urbains. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c5111c9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4c5111c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-5f9a9880\" data-id=\"5f9a9880\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-a142c52\" data-id=\"a142c52\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f05ee5c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3f05ee5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#ESSENTIEL\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En r\u00e9sum\u00e9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-2b0e60fe\" data-id=\"2b0e60fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4618a27a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4618a27a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#SPECIFICITES\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zoom<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-309a4171\" data-id=\"309a4171\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cbd85c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2cbd85c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#AUTONOMIE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Autonomie<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-6fc8f749\" data-id=\"6fc8f749\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b2cbf74 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1b2cbf74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#TAILLE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tailles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-31a3ccc1\" data-id=\"31a3ccc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29c6c84 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"29c6c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#INFOCOMP\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Caract\u00e9ristiques<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-4268dc63\" data-id=\"4268dc63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41855661 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"41855661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#IMMERSIONS\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">#feelgood<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-12 elementor-top-column elementor-element elementor-element-297ec045\" data-id=\"297ec045\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e6b3d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e6b3d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e71a858\" data-id=\"e71a858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa1a513 elementor-widget elementor-widget-spacer\" data-id=\"fa1a513\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a93a630 elementor-widget elementor-widget-menu-anchor\" data-id=\"a93a630\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ESSENTIEL\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f1133f0 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"6f1133f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37d2ab50\" data-id=\"37d2ab50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13562d54 elementor-widget elementor-widget-image\" data-id=\"13562d54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2023\/03\/o2feel-couverture-iswan-city-boost-7-1.jpg\" class=\"attachment-large size-large wp-image-59945\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-760ce64c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"760ce64c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18790a2e\" data-id=\"18790a2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3239fbaa elementor-view-stacked elementor-absolute animated-slow elementor-shape-circle elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"3239fbaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-bounce-in\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDgxNzcsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f8c0208 elementor-view-stacked elementor-absolute animated-slow elementor-shape-circle elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"3f8c0208\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-bounce-in\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDgxNTksInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31fd238f elementor-view-stacked elementor-absolute animated-slow elementor-shape-circle elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"31fd238f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-bounce-in\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDgxNjUsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b96fa81 elementor-view-stacked elementor-absolute animated-slow elementor-shape-circle elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"3b96fa81\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-bounce-in\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDgxNzEsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55d51139 elementor-widget elementor-widget-image\" data-id=\"55d51139\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-93573\" alt=\"\" srcset=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-1024x1024.jpg 1024w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-300x300.jpg 300w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-150x150.jpg 150w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-768x768.jpg 768w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-154x154.jpg 154w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-500x500.jpg 500w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-800x800.jpg 800w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-120x120.jpg 120w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-50x50.jpg 50w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1-100x100.jpg 100w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2021\/06\/iSwan-7-1-BP-1200x1200-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-496098c3\" data-id=\"496098c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14612bc0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"14612bc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-778641f5\" data-id=\"778641f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-174308e9 elementor-widget elementor-widget-text-editor\" data-id=\"174308e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEn\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-392aca34 elementor-widget elementor-widget-heading\" data-id=\"392aca34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00c9SUM\u00c9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51fa20f2\" data-id=\"51fa20f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6223d1d6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6223d1d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1afc3f29 elementor-hidden-mobile\" data-id=\"1afc3f29\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32e105f1\" data-id=\"32e105f1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99745f6 elementor-widget elementor-widget-spacer\" data-id=\"99745f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5afed3cd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5afed3cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3 tailles : 26\"S, 28\"M, 28\"L<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3 couleurs : Gris Anthracite, Bleu Cosmique, Marron Glac\u00e9<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Moyeu : Shimano Nexus 5 vitesses<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Courroie : Carbon Gates<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d739a13 elementor-widget elementor-widget-spacer\" data-id=\"5d739a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26616651 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"26616651\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6542382f\" data-id=\"6542382f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-698d343d elementor-widget elementor-widget-image\" data-id=\"698d343d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-1024x512.jpg\" class=\"attachment-large size-large wp-image-78309\" alt=\"\" srcset=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-1024x512.jpg 1024w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-300x150.jpg 300w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-768x384.jpg 768w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-1536x768.jpg 1536w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-2048x1024.jpg 2048w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-220x110.jpg 220w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-1920x960.jpg 1920w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2024\/03\/Cartouche-4ans-VFR-NoirsurBlanc-1-800x400.jpg 800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34dcb129\" data-id=\"34dcb129\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dd1142f elementor-widget elementor-widget-text-editor\" data-id=\"5dd1142f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBatterie\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-267b997f elementor-widget elementor-widget-heading\" data-id=\"267b997f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4 ans DE GARANTIE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-45242154 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45242154\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-154e7b48\" data-id=\"154e7b48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-517f84fd elementor-widget elementor-widget-text-editor\" data-id=\"517f84fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous ma\u00eetrisons :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2121e509\" data-id=\"2121e509\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b214aa9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2b214aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Technologie lithium<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cellule 21700 derni\u00e8re g\u00e9n\u00e9ration<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Software neutralisant la d\u00e9charge profonde<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b20924e elementor-widget elementor-widget-text-editor\" data-id=\"5b20924e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEn bref : L\u2019ensemble de nos batteries sont garanties 4 ans\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58a2c7ee elementor-widget elementor-widget-text-editor\" data-id=\"58a2c7ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPensez \u00e0 vous enregistrer\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86edb07 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"86edb07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-bounce-in\" href=\"https:\/\/www.o2feel.com\/4-ans-de-garantie\/\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4713883 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4713883\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b756bc\" data-id=\"8b756bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66bff71 elementor-widget elementor-widget-spacer\" data-id=\"66bff71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd65f50 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fd65f50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22c6e205\" data-id=\"22c6e205\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-799c0fdc elementor-widget elementor-widget-menu-anchor\" data-id=\"799c0fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"SPECIFICITES\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3006ab4a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3006ab4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-641ef347\" data-id=\"641ef347\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c362dbf testtest elementor-widget elementor-widget-heading\" data-id=\"3c362dbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ZOOM<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-486a5186\" data-id=\"486a5186\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dcf9058 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"5dcf9058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c3b09cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c3b09cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62e9f2fe\" data-id=\"62e9f2fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-794acf0c elementor-hidden-mobile elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"794acf0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:2000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-cc52b08 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_moteur\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-shimano\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Moteur<\/div><div class=\"elementor-slide-description\"><p>Moteur Shimano E6100<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-b2e72b5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_batterie\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/developpement-o2feel-les-batteries\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Batterie<\/div><div class=\"elementor-slide-description\"><p>Batterie iPowerPack 432\/540<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-8b929ad swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_courroie\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-gates\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Courroie<\/div><div class=\"elementor-slide-description\"><p>Courroie Carbon Drive<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-d5d4935 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_Freins\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-shimano\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Freins<\/div><div class=\"elementor-slide-description\"><p>Freins Shimano MT200<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-ff7c61c swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_pneu\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-schwalbe\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Pneus<\/div><div class=\"elementor-slide-description\"><p>Pneus Schwalbe Road Cruiser<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-a039c44 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_selle_tige\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/technologies\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Selle<\/div><div class=\"elementor-slide-description\"><p>Selle Ergon<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-054f67a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_cadenas\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/technologies\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Antivol<\/div><div class=\"elementor-slide-description\"><p>Antivol AXA<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-f4a9d9e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_compteur\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/technologies\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Poign\u00e9es<\/div><div class=\"elementor-slide-description\"><p>Poign\u00e9es Grip<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-c820cf4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_porte-bagae\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-mik\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Porte-bagages<\/div><div class=\"elementor-slide-description\"><p>Porte-bagages MIK HD<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-c4d245f swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_fourche\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-srsuntour\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Fourche<\/div><div class=\"elementor-slide-description\"><p>Fourche Suntour NEX<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09c90d5 elementor-hidden-desktop elementor-hidden-tablet elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"09c90d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:2000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-cc52b08 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_moteur\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-shimano\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Moteur<\/div><div class=\"elementor-slide-description\"><p>Moteur Shimano E6100<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-b2e72b5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_batterie\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/developpement-o2feel-les-batteries\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Batterie<\/div><div class=\"elementor-slide-description\"><p>Batterie iPowerPack 432\/540<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-8b929ad swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_courroie\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-gates\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Courroie<\/div><div class=\"elementor-slide-description\"><p>Courroie Carbon Drive<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-d5d4935 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_Freins\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-shimano\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Freins<\/div><div class=\"elementor-slide-description\"><p>Freins Shimano MT200<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-ff7c61c swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_pneu\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-schwalbe\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Pneus<\/div><div class=\"elementor-slide-description\"><p>Pneus Schwalbe Road Cruiser<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-a039c44 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_selle_tige\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/technologies\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Selle<\/div><div class=\"elementor-slide-description\"><p>Selle Ergon<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-054f67a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_cadenas\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/technologies\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Antivol<\/div><div class=\"elementor-slide-description\"><p>Antivol AXA<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-f4a9d9e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_compteur\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/technologies\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Poign\u00e9es<\/div><div class=\"elementor-slide-description\"><p>Poign\u00e9es Grip<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-c820cf4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_porte-bagae\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-mik\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Porte-bagages<\/div><div class=\"elementor-slide-description\"><p>Porte-bagages MIK HD<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-c4d245f swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"iSwan_City_Boost_7.1_fourche\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.o2feel.com\/partenaire-o2feel-srsuntour\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Fourche<\/div><div class=\"elementor-slide-description\"><p>Fourche Suntour NEX<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">En savoir plus<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40231bb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40231bb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-115262e9\" data-id=\"115262e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a2578d3 elementor-widget elementor-widget-spacer\" data-id=\"2a2578d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d66754f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d66754f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37dcf7fe\" data-id=\"37dcf7fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db7051a elementor-widget elementor-widget-menu-anchor\" data-id=\"db7051a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"AUTONOMIE\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a924ec5 elementor-widget elementor-widget-spacer\" data-id=\"4a924ec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66f9f355 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"66f9f355\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-35e61ca2\" data-id=\"35e61ca2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49d9d169 elementor-widget elementor-widget-heading\" data-id=\"49d9d169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COMBIEN DE KM ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-225e8657\" data-id=\"225e8657\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14713ff6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14713ff6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b408eaf\" data-id=\"2b408eaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c31e627 elementor-widget elementor-widget-spacer\" data-id=\"c31e627\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1da13471 elementor-widget elementor-widget-image\" data-id=\"1da13471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"663\" src=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2023\/10\/Autonomie.jpg\" class=\"attachment-full size-full wp-image-72095\" alt=\"\" srcset=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2023\/10\/Autonomie.jpg 1000w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2023\/10\/Autonomie-300x199.jpg 300w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2023\/10\/Autonomie-768x509.jpg 768w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2023\/10\/Autonomie-220x146.jpg 220w, https:\/\/www.o2feel.com\/wp-content\/uploads\/2023\/10\/Autonomie-800x530.jpg 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d2e3876\" data-id=\"1d2e3876\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cd5fb78 elementor-widget elementor-widget-spacer\" data-id=\"7cd5fb78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3937b653 elementor-widget elementor-widget-text-editor\" data-id=\"3937b653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;autonomie correspond au nombre moyen de kilom\u00e8tres que vous pourrez r\u00e9aliser entre chaque temps de charge.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68f09a3c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"68f09a3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.o2feel.com\/ch\/autonomie-o2feel\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Faire un test sur notre simulateur<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55be407d elementor-widget elementor-widget-text-editor\" data-id=\"55be407d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;autonomie d&#8217;un v\u00e9lo \u00e9lectrique d\u00e9pend de plusieurs facteurs, tels que la capacit\u00e9 de la batterie, le poids du v\u00e9lo et du cycliste, le niveau d&#8217;assistance utilis\u00e9 ou encore les conditions de conduite.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61bd21c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61bd21c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ef5bd4e\" data-id=\"6ef5bd4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4010c3eb elementor-widget elementor-widget-spacer\" data-id=\"4010c3eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c506bc3 elementor-widget elementor-widget-menu-anchor\" data-id=\"5c506bc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"TAILLE\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c2386e9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7c2386e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-286c3e44\" data-id=\"286c3e44\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d9d57e4 elementor-widget elementor-widget-spacer\" data-id=\"4d9d57e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21e70109 elementor-widget elementor-widget-heading\" data-id=\"21e70109\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S \/ M \/ L ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6586bccf elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"6586bccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56a69867 elementor-widget elementor-widget-heading\" data-id=\"56a69867\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O2FEEL vous guide dans le choix de votre taille de v\u00e9lo.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2db6420f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2db6420f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.o2feel.com\/ch\/guides-des-tailles\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Guide des tailles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2555670b elementor-widget elementor-widget-spacer\" data-id=\"2555670b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-182f24c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"182f24c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7be0917f\" data-id=\"7be0917f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-576ca2ae elementor-widget elementor-widget-spacer\" data-id=\"576ca2ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66b40988 elementor-widget elementor-widget-menu-anchor\" data-id=\"66b40988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"INFOCOMP\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70667045 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"70667045\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44e88336\" data-id=\"44e88336\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f7b430 elementor-widget elementor-widget-text-editor\" data-id=\"4f7b430\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPour les\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-118b915c elementor-widget elementor-widget-heading\" data-id=\"118b915c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SP\u00c9CIALISTES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de9d462 elementor-widget elementor-widget-text-editor\" data-id=\"de9d462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCaract\u00e9ristiques\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ab0acd4\" data-id=\"ab0acd4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56eae021 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56eae021\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d40e044\" data-id=\"4d40e044\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3381c655 elementor-widget elementor-widget-spacer\" data-id=\"3381c655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f57dd8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f57dd8c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69fe1fd0\" data-id=\"69fe1fd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61887c02 elementor-widget elementor-widget-woocommerce-product-additional-information\" data-id=\"61887c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-product-additional-information.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t<h2>Additional information<\/h2>\n\n<table class=\"woocommerce-product-attributes shop_attributes\" aria-label=\"Product Details\">\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_moteur\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Moteur<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/moteur\/shimano-steps-e6100\/\" rel=\"tag\">Shimano STEPS E6100<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_batterie\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Batterie<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/batterie\/ipowerpack-540\/\" rel=\"tag\">iPowerPack 540<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_autonomie\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Autonomie<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/autonomie\/jusqua-180km\/\" rel=\"tag\">jusqu&#039;\u00e0 180km<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_compteur\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Compteur<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/compteur\/display-lcd-lateral-shimano-fixe-au-guidon-sur-la-gauche-fixe-pas-de-vol-et-possibilite-de-panier-a-lavant\/\" rel=\"tag\">Display LCD lat\u00e9ral Shimano, fix\u00e9 au guidon sur la gauche. Fixe (pas de vol) et possibilit\u00e9 de panier \u00e0 l&#039;avant<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_moyeu\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Moyeu<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/moyeu\/nexus-5e-5-vitesses-integrees-offre-un-changement-de-vitesses-haute-performance-une-compatibilite-parfaite-avec-un-moteur-central\/\" rel=\"tag\">NEXUS 5E : 5 vitesses int\u00e9gr\u00e9es, offre un changement de vitesses haute performance, une compatibilit\u00e9 parfaite avec un moteur central<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_plateau\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Plateau\/Pignon<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/plateau\/pignon-gates-cdx-39-dents\/\" rel=\"tag\">Pignon Gates CDX 39 dents<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_manette\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Manette<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/manette\/poignee-tournante-shimano-facile-dutilisation\/\" rel=\"tag\">Poign\u00e9e tournante Shimano facile d&#039;utilisation<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_transmission\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Transmission<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/transmission\/courroie-cdx-gates-carbon-drive-ultra-resistante-silencieuse-et-peu-dentretien\/\" rel=\"tag\">Courroie fibre de carbone, ultra resistante, silencieuse et peu d&#039;entretien<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_cadre\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Cadre<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/cadre\/aluminium-6061-a-enjambement-ultra-bas-finition-slick-shape\/\" rel=\"tag\">Aluminium 6061 \u00e0 enjambement ultra bas, finition Slick Shape<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_fourche\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Fourche<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/fourche\/suntour-nex-suspendue\/\" rel=\"tag\">Suntour NEX suspendue<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_freins\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Freins<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/freins\/disque-hydrauliques-shimano-mt200\/\" rel=\"tag\">Disque hydrauliques Shimano MT200<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_jantes\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Jantes<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/jantes\/rodi-double-paroi-specifiques-e-bike\/\" rel=\"tag\">Rodi double paroi, sp\u00e9cifiques e-bike<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_pneus\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Pneus<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/pneus\/schwalbe-road-cruiser-k-guard-anti-crevaison-avec-bande-reflechissante-issus-de-matieres-premieres-renouvelables-et-recyclees-26\/\" rel=\"tag\">Schwalbe Road Cruiser K-Guard* anti-crevaison avec bande r\u00e9fl\u00e9chissante, issus de mati\u00e8res premi\u00e8res renouvelables et recycl\u00e9es (26&quot;x1.75 ou 28&quot;x1.75)<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_tige-de-selle\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Tige de selle<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/tige-de-selle\/satori-avec-suspension-ajustable-en-hauteur-avec-outil\/\" rel=\"tag\">Satori avec suspension, ajustable en hauteur avec outil<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_selle\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Selle<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/selle\/selle-royal-lookin-coussinets-en-gel\/\" rel=\"tag\">Selle Royal Lookin, coussinets en gel<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_potence\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Potence<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/potence\/satori-ajustable-angle-40-a-140\/\" rel=\"tag\">Satori ajustable, Angle : 40\u00b0 \u00e0 140\u00b0<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_poignees\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Poignees<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/poignees\/selle-royal-en-simili-cuir\/\" rel=\"tag\">Selle Royal en simili cuir<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_pedales\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Pedales<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/pedales\/aluminium-wellgo-anti-derapantes-avec-reflecteurs\/\" rel=\"tag\">Aluminium Wellgo anti-d\u00e9rapantes avec r\u00e9flecteurs<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_eclairage-av\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Eclairage AV<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/eclairage-av\/axa-blue-line-30-lux\/\" rel=\"tag\">AXA Blue line 30 Lux<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_eclairage-ar\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Eclairage AR<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/eclairage-ar\/spanninga-communter-glow-integree-dans-le-porte-bagage\/\" rel=\"tag\">Spanninga Communter Glow int\u00e9gr\u00e9e dans le porte bagage<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_garde-boue\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Garde-boue<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/garde-boue\/acier-assortis-a-la-couleur-du-cadre-avec-molette-pour-ajustement-facile\/\" rel=\"tag\">Acier assortis \u00e0 la couleur du cadre avec molette pour ajustement facile<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_porte-bagage\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Porte-bagages<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/porte-bagage\/mik-hd-compatible-siege-bebe-poids-max-27kg\/\" rel=\"tag\">MIK HD compatible si\u00e8ge b\u00e9b\u00e9 Poids max 27Kg<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_bequille\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Bequille<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/bequille\/laterale\/\" rel=\"tag\">Lat\u00e9rale<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_antivol-de-cadre\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Antivol de cadre<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/antivol-de-cadre\/axa-solid-plus-compatible-chaine-plug-in\/\" rel=\"tag\">AXA Solid Plus compatible cha\u00eene plug-in<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_disques-av-ar\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Disques AV\/AR<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/disques-av-ar\/shimano-160-160-mm\/\" rel=\"tag\">Shimano 160\/160 mm<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_couleurs\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Couleurs<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/couleurs\/gris-anthracite\/\" rel=\"tag\">Gris Anthracite<\/a>, <a href=\"https:\/\/www.o2feel.com\/ch\/couleurs\/bleu-cosmique\/\" rel=\"tag\">Bleu Cosmique<\/a>, <a href=\"https:\/\/www.o2feel.com\/ch\/couleurs\/marron-glace\/\" rel=\"tag\">Marron glac\u00e9<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_type-de-cadre\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Type de cadre<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/type-de-cadre\/cadre-bas-univ\/\" rel=\"tag\">Cadre bas (Univ)<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t\t\t<tr class=\"woocommerce-product-attributes-item woocommerce-product-attributes-item--attribute_pa_tailles-simpliees\">\n\t\t\t<th class=\"woocommerce-product-attributes-item__label\" scope=\"row\">Tailles simplifees<\/th>\n\t\t\t<td class=\"woocommerce-product-attributes-item__value\"><p><a href=\"https:\/\/www.o2feel.com\/ch\/tailles-simpliees\/s\/\" rel=\"tag\">S<\/a>, <a href=\"https:\/\/www.o2feel.com\/ch\/tailles-simpliees\/m\/\" rel=\"tag\">M<\/a>, <a href=\"https:\/\/www.o2feel.com\/ch\/tailles-simpliees\/l\/\" rel=\"tag\">L<\/a><\/p>\n<\/td>\n\t\t<\/tr>\n\t<\/table>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a475a2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a475a2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a0c05e1\" data-id=\"2a0c05e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cbeb149 elementor-widget elementor-widget-spacer\" data-id=\"7cbeb149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-731fe7c elementor-widget elementor-widget-menu-anchor\" data-id=\"731fe7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"IMMERSIONS\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26ca2382 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"26ca2382\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-271d375f\" data-id=\"271d375f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13606a62 elementor-widget elementor-widget-heading\" data-id=\"13606a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">#FEELGOOD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94ab7bc elementor-widget elementor-widget-text-editor\" data-id=\"94ab7bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>#O2feel#qualit\u00e9devie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-170d49c2\" data-id=\"170d49c2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f1d544d elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f1d544d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83ade3\" data-id=\"83ade3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29c2de5d elementor-widget elementor-widget-spacer\" data-id=\"29c2de5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24c4419 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24c4419\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-91753b8\" data-id=\"91753b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2280c56 elementor-widget elementor-widget-gallery\" data-id=\"2280c56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:3,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;image_hover_animation&quot;:&quot;move-contained-top&quot;,&quot;columns_mobile&quot;:2,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns_tablet&quot;:2,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1264O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2280c56\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE4NjksInVybCI6Imh0dHBzOlwvXC93d3cubzJmZWVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDVcLzIzMDYyMDIxLURTQ18xMjY0TzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxTzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxLmpwZyIsInNsaWRlc2hvdyI6IjIyODBjNTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1264O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-width=\"533\" data-height=\"800\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1497O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2280c56\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE4ODUsInVybCI6Imh0dHBzOlwvXC93d3cubzJmZWVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDVcLzIzMDYyMDIxLURTQ18xNDk3TzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxTzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxLmpwZyIsInNsaWRlc2hvdyI6IjIyODBjNTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1497O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1275O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2280c56\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE4NzMsInVybCI6Imh0dHBzOlwvXC93d3cubzJmZWVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDVcLzIzMDYyMDIxLURTQ18xMjc1TzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxTzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxLmpwZyIsInNsaWRlc2hvdyI6IjIyODBjNTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1275O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1281O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2280c56\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE4NzcsInVybCI6Imh0dHBzOlwvXC93d3cubzJmZWVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDVcLzIzMDYyMDIxLURTQ18xMjgxTzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxTzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxLmpwZyIsInNsaWRlc2hvdyI6IjIyODBjNTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1281O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-width=\"800\" data-height=\"533\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1494O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2280c56\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzE4ODEsInVybCI6Imh0dHBzOlwvXC93d3cubzJmZWVsLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDVcLzIzMDYyMDIxLURTQ18xNDk0TzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxTzJmZWVsLW1hcnNlaWxsZS0wNi0yMDIxLmpwZyIsInNsaWRlc2hvdyI6IjIyODBjNTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.o2feel.com\/wp-content\/uploads\/2022\/05\/23062021-DSC_1494O2feel-marseille-06-2021O2feel-marseille-06-2021.jpg\" data-width=\"800\" data-height=\"816\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cc1630b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cc1630b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31a9c45f\" data-id=\"31a9c45f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17129a78 elementor-widget elementor-widget-spacer\" data-id=\"17129a78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-365aed49 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"365aed49\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-600da558\" data-id=\"600da558\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:77973,&quot;url&quot;:&quot;https:\\\/\\\/www.o2feel.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Footer-page-produit-Trouver-Revendeur.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65351ab4 elementor-widget elementor-widget-spacer\" data-id=\"65351ab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73a0866e elementor-widget elementor-widget-heading\" data-id=\"73a0866e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TROUVER VOTRE REVENDEUR O2FEEL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d146d75 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"7d146d75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-shrink\" href=\"https:\/\/www.o2feel.com\/revendeurs\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12b999c2 elementor-widget elementor-widget-spacer\" data-id=\"12b999c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-212abf59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"212abf59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-713b649b\" data-id=\"713b649b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27dff9d4 elementor-widget elementor-widget-spacer\" data-id=\"27dff9d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div class=\"product-desc\"> P\u00e9dalez sans contrainte <\/div>\n","protected":false},"featured_media":93573,"template":"","meta":[],"product_brand":[],"product_cat":[2499],"product_tag":[],"class_list":{"0":"post-46223","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-promotions","7":"pa_antivol-de-cadre-axa-solid-plus-compatible-chaine-plug-in","8":"pa_autonomie-jusqua-180km","9":"pa_batterie-ipowerpack-540","10":"pa_bequille-laterale","11":"pa_cadre-aluminium-6061-a-enjambement-ultra-bas-finition-slick-shape","12":"pa_compteur-display-lcd-lateral-shimano-fixe-au-guidon-sur-la-gauche-fixe-pas-de-vol-et-possibilite-de-panier-a-lavant","13":"pa_couleurs-bleu-cosmique","14":"pa_couleurs-gris-anthracite","15":"pa_couleurs-marron-glace","16":"pa_disques-av-ar-shimano-160-160-mm","17":"pa_eclairage-ar-spanninga-communter-glow-integree-dans-le-porte-bagage","18":"pa_eclairage-av-axa-blue-line-30-lux","19":"pa_fourche-suntour-nex-suspendue","20":"pa_freins-disque-hydrauliques-shimano-mt200","21":"pa_garde-boue-acier-assortis-a-la-couleur-du-cadre-avec-molette-pour-ajustement-facile","22":"pa_jantes-rodi-double-paroi-specifiques-e-bike","23":"pa_manette-poignee-tournante-shimano-facile-dutilisation","24":"pa_modele-iswan-ch","25":"pa_moteur-shimano-steps-e6100","26":"pa_moyeu-nexus-5e-5-vitesses-integrees-offre-un-changement-de-vitesses-haute-performance-une-compatibilite-parfaite-avec-un-moteur-central","27":"pa_pedales-aluminium-wellgo-anti-derapantes-avec-reflecteurs","28":"pa_plateau-pignon-gates-cdx-39-dents","29":"pa_pneus-schwalbe-road-cruiser-k-guard-anti-crevaison-avec-bande-reflechissante-issus-de-matieres-premieres-renouvelables-et-recyclees-26","30":"pa_poignees-selle-royal-en-simili-cuir","31":"pa_porte-bagage-mik-hd-compatible-siege-bebe-poids-max-27kg","32":"pa_potence-satori-ajustable-angle-40-a-140","33":"pa_selle-selle-royal-lookin-coussinets-en-gel","34":"pa_tailles-simpliees-l","35":"pa_tailles-simpliees-m","36":"pa_tailles-simpliees-s","37":"pa_tige-de-selle-satori-avec-suspension-ajustable-en-hauteur-avec-outil","38":"pa_transmission-courroie-cdx-gates-carbon-drive-ultra-resistante-silencieuse-et-peu-dentretien","39":"pa_type-de-cadre-cadre-bas-univ","41":"first","42":"instock","43":"shipping-taxable","44":"purchasable","45":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product\/46223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product\/46223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/media\/93573"}],"wp:attachment":[{"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/media?parent=46223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product_brand?post=46223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product_cat?post=46223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.o2feel.com\/ch\/wp-json\/wp\/v2\/product_tag?post=46223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}